{"id":232336,"date":"2021-05-10T17:49:19","date_gmt":"2021-05-10T17:49:19","guid":{"rendered":"https:\/\/www.yutaniglobal.com\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/"},"modified":"2021-05-10T17:50:32","modified_gmt":"2021-05-10T17:50:32","slug":"consejos-para-el-reemplazo-de-la-cadena-de-oruga","status":"publish","type":"post","link":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/","title":{"rendered":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97720ee83db\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97720ee83db\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#%C2%BFCOMO_REMPLAZAR_LAS_PISTAS_DE_UNA_BULLDOZER\" >\u00bfC\u00d3MO REMPLAZAR LAS PISTAS DE UNA BULLDOZER?<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#LIBERAR_LA_TENSION_DE_LA_PISTA\" >LIBERAR LA TENSI\u00d3N DE LA PISTA.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ENLACE_DE_PIN_MAESTRO\" >ENLACE DE PIN MAESTRO<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ENLACE_MAESTRO_DIVIDIDO\" >ENLACE MAESTRO DIVIDIDO<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#OBSERVACION\" >OBSERVACI\u00d3N<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#REEMPLAZO_DE_PISTAS\" >REEMPLAZO DE PISTAS<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#CONSEJOS\" >CONSEJOS<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#RODILLOS_Y_RUEDAS_LOCAS\" >RODILLOS Y RUEDAS LOCAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#CADENAS_AGRUPADAS\" >CADENAS AGRUPADAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ZAPATAS\" >ZAPATAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#CADENAS_RESBALANDOSE_DE_LOS_PINONES\" >CADENAS RESBALANDOSE DE LOS PI\u00d1ONES<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#PROBLEMAS_COMUNES_EN_TRENES_DE_RODAJES\" >PROBLEMAS COMUNES EN TRENES DE RODAJES<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#PISTAS_DE_ENLACES\" >PISTAS DE ENLACES<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#EXCESIVO_DESGASTE_DEL_RIEL_LATERAL\" >EXCESIVO DESGASTE DEL RIEL LATERAL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#INDENTACIONES_EN_SUPERFICIE_INTERNA_DE_CARRIL\" >INDENTACIONES EN SUPERFICIE INTERNA DE CARRIL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESGASTE_LATERAL_DEL_PIN_MAESTRO\" >DESGASTE LATERAL DEL PIN MAESTRO<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESGASTE_FACIAL_EXCESIVO\" >DESGASTE FACIAL EXCESIVO<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ESQUINAS_DE_RIEL_GOLPEADAS\" >ESQUINAS DE RIEL GOLPEADAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#GRIETAS_O_ROTURAS_EN_LAS_ZONAS_CON_MAYORES_ESFUERZOS\" >GRIETAS O ROTURAS EN LAS ZONAS CON MAYORES ESFUERZOS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DEFORMACION_DEL_CASQUILLO_ANTERIOR_Y_PASADOR\" >DEFORMACI\u00d3N DEL CASQUILLO ANTERIOR Y PASADOR<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#PASADORES_Y_ARBUSTOS_DEL_TIPO_RELLENO_DE_GRASA\" >PASADORES Y ARBUSTOS DEL TIPO RELLENO DE GRASA<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESGASTE_DEL_EXTREMO_FINAL_DEL_PASADOR\" >DESGASTE DEL EXTREMO FINAL DEL PASADOR<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#PASADORES_SUELTOS\" >PASADORES SUELTOS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ROTURAS_DE_PASADOR\" >ROTURAS DE PASADOR<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESCASCARAMIENTO_DEL_PASADOR\" >DESCASCARAMIENTO DEL PASADOR<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#RODILLOS_INFERIORES_DE_LA_PISTA\" >RODILLOS INFERIORES DE LA PISTA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESGASTE_EXCESIVO_DE_LA_BRIDA_LATERAL\" >DESGASTE EXCESIVO DE LA BRIDA LATERAL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DEFORMACION_DE_LA_BRIDA_SUPERIOR\" >DEFORMACI\u00d3N DE LA BRIDA SUPERIOR<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#ZAPATAS-2\" >ZAPATAS<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#DESGASTE_ACELERADO_DE_SUPERFICIES_SUPERPUESTAS\" >DESGASTE ACELERADO DE SUPERFICIES SUPERPUESTAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#AGUJEROS_PARA_PERNOS_AMPLIADOS\" >AGUJEROS PARA PERNOS AMPLIADOS<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb][et_pb_row _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h4><span class=\"ez-toc-section\" id=\"%C2%BFCOMO_REMPLAZAR_LAS_PISTAS_DE_UNA_BULLDOZER\"><\/span>\u00bfC\u00d3MO REMPLAZAR LAS PISTAS DE UNA BULLDOZER?<span class=\"ez-toc-section-end\"><\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>El reemplazo de la cadena de cadenas es importante. Para reemplazar alg\u00fan elemento del tren de rodaje es necesario retirar la oruga, incluso en el caso que se requiera remplazarlo, o cuando se realicen mantenimientos y reparaciones en el tren de rodaje. Para poder extraer las pistas se debe conocer el tipo de enlace maestro. En m\u00e1quinas topadoras existen dos tipos de enlaces maestros: enlace maestro dividido y enlace de pasador maestro.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"LIBERAR_LA_TENSION_DE_LA_PISTA\"><\/span>LIBERAR LA TENSI\u00d3N DE LA PISTA.<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Para remover las orugas, es necesario levantar el equipo. Coloque una gata hidr\u00e1ulica en la parte trasera del <br>equipo y eleve la parte posterior, se puede ayudar de la pluma de la excavadora para levantarla desde el suelo. Posteriormente, ubique una madera contrachapada o tapetes para prevenir da\u00f1os en el piso y mantener las piezas limpias. Utilice el tensor de orugas para aflojar las orugas; esto facilita la remoci\u00f3n de las pistas. Se libera la tensi\u00f3n retrocediendo manualmente el ajustador de la oruga o aflojando el tornillo del ajustador.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"ENLACE_DE_PIN_MAESTRO\"><\/span>ENLACE DE PIN MAESTRO<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Posteriormente, remueve la cubierta lateral que se encuentra localizada aproximadamente en un punto medio entre las dos para poder acceder a la tuerca de apriete de la rueda loca. Emplee una llave para aflojar la tuerca de ajuste de la rueda loca. Ubique la posici\u00f3n de los pines maestros, a simple vista son ligeramente diferente al resto de los pines de la cadena, emplee un removedor de pernos. El pasador maestro se puede reconocer ya que tiene un dispositivo de bloqueo o un orificio perforado en uno de los extremos que permite diferenciarlo de los dem\u00e1s de pasadores de la cadena. Movilice el equipo hacia atr\u00e1s lentamente o, en algunos modelos, hacia adelante para llevar el pasador maestro justo debajo del nivel de la barra de tiro. Coloque un bloque debajo de la garra en una zapata que permita que el pasador maestro se centre en la rueda polea delantera. Con el pasador maestro centrado en la polea tensora delantera, retire cualquier dispositivo de bloqueo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Existen diversas opciones para remover el pin maestro, puede emplear una prensa port\u00e1til para remover los pernos que unen los dos lados del pin maestro, otra opci\u00f3n, es calentar el \u00e1rea y con la ayuda de un martillo y una placa perforadora darle un golpe, la \u00faltima opci\u00f3n consiste en cortar el enlace con un soplete (si se est\u00e1 realizando un remplazo se deber\u00e1 soldar despu\u00e9s).<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Luego localice el ajustador de la polea tensora, en ocasiones puede estar protegida con una cubierta, afloje el ajustador de la polea. En funci\u00f3n del tama\u00f1o de la m\u00e1quina se requiere emplear un cabrestante, una gr\u00faa, un montacarga o un cargador con accesorios para que realice el trabajo pesado. Retire la parte delantera de las orugas y p\u00f3ngalas junto a la parte delantera del tren de aterrizaje. Si ha levantado toda la m\u00e1quina, h\u00e1galo funcionar en reversa; esto apilar\u00e1 la pista cerca de la parte trasera de la m\u00e1quina. Utilice el mismo m\u00e9todo para la otra pista. Luego use una carretilla elevadora para quitar las orugas de la m\u00e1quina.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"ENLACE_MAESTRO_DIVIDIDO\"><\/span>ENLACE MAESTRO DIVIDIDO<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>El enlace maestro se compone de dos piezas entrelazadas. Una pieza est\u00e1 unida a un extremo de las pistas y la otra pieza est\u00e1 unida al otro extremo de las pistas. Separa las dos piezas. Es posible que deba golpear los eslabones con un martillo para aflojarlos. Ahora las pistas ya no est\u00e1n conectadas en c\u00edrculo. Quite las pistas tirando de la pista inferior en la direcci\u00f3n de la parte trasera de la m\u00e1quina.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"OBSERVACION\"><\/span>OBSERVACI\u00d3N<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Las orugas son pesadas y es muy probable que sea muy dif\u00edcil para usted extraerla a mano (especialmente en m\u00e1quinas m\u00e1s grandes). Los contratistas que no tienen una m\u00e1quina que realice este trabajo encadenar\u00e1n las orugas a un veh\u00edculo y luego \u00absacar\u00e1n\u00bb las orugas de la m\u00e1quina. Despu\u00e9s de quitar las orugas, aseg\u00farese siempre de que la m\u00e1quina siempre est\u00e9 bloqueada de tal manera que sea segura mientras se realizan las reparaciones. Siempre que se retire una oruga, inspeccione minuciosamente los componentes del bastidor de la oruga para ver si hay desgaste excesivo y desalineaci\u00f3n. La extracci\u00f3n, el desmontaje y el reemplazo var\u00edan seg\u00fan el modelo y el fabricante. Consulte el manual de servicio del fabricante para conocer los procedimientos exactos.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"REEMPLAZO_DE_PISTAS\"><\/span>REEMPLAZO DE PISTAS<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Para reemplazar las orugas, retire la m\u00e1quina de la tabla y col\u00f3quelo en las nuevas orugas para que la rueda dentada motriz encaje correctamente con el riel. Contin\u00fae retrocediendo hasta que el equipo est\u00e9 justo delante del extremo trasero de la pista. A continuaci\u00f3n, coloque una barra en la oruga y ayude a la oruga a trepar sobre la rueda dentada, los rodillos portadores y la polea tensora mientras el tractor avanza. Cuando la pista se junta, instale el pasador maestro y cualquier dispositivo de bloqueo. Una vez que la pista est\u00e9 junta, ajuste la tensi\u00f3n de la pista utilizando los procedimientos recomendados por el fabricante.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h4><span class=\"ez-toc-section\" id=\"CONSEJOS\"><\/span>CONSEJOS<span class=\"ez-toc-section-end\"><\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"RODILLOS_Y_RUEDAS_LOCAS\"><\/span>RODILLOS Y RUEDAS LOCAS<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>No es recomendable mezclar rodillos nuevos con algunos ya usados en el mismo lado debido a que se puede producir una sobrecarga en los nuevo, al estar en operaci\u00f3n los rodillos nuevos se asentar\u00e1n m\u00e1s que los viejos debido a un factor de desgaste, lo que genera que conlleven un peso mucho mayor.<\/li>\n<li>En el caso de que no se reemplacen todos los rodillos inferiores por unos nuevos es recomendable colocar los rodillos desgastados, pero a\u00fan \u00fatiles en un lado y todos los rodillos nuevos en el otro lado, esto permite que la presi\u00f3n que se produzca en cada uno de los rodillos sea proporcional sin producirse una sobrecarga individual.<\/li>\n<li>Por precauci\u00f3n se recomienda que durante las primeras 100 horas de reemplazo de rodillos y ruedas locas no se recorran grandes trayectos de manera continua, es necesario realizar paradas de la m\u00e1quina con frecuencia para evitar que se sobrecaliente y se atasque. Realice paradas cada 4-5 minutos y dir\u00edjase a la direcci\u00f3n contraria para asegurar la circulaci\u00f3n del aceite.<\/li>\n<\/ul>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"CADENAS_AGRUPADAS\"><\/span>CADENAS AGRUPADAS<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Puede ser generado por las condiciones de trabajo, en el caso especialmente que se realicen en zonas h\u00famedas, o tambi\u00e9n porque la m\u00e1quina esta asentada, sin movimiento, por largos periodos, lo que genera que la humedad ingrese provocando que los sellos se agarroten, una soluci\u00f3n posible es extraer los pasadores de la oruga, re-engrasar y empujar hacia dentro. Provocar vibraciones controladas tambi\u00e9n puede servir para aflojarla.<\/li>\n<\/ul>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"ZAPATAS\"><\/span>ZAPATAS<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Para poder tener una flotaci\u00f3n adecuada se recomienda emplear la zapata m\u00e1s estrecha posible.<\/li>\n<li>Recuerde que el contacto entre las zapatas y las cadenas debe ser de metal con metal, ya que en caso de no cumplirse los penos se aflojar\u00e1n y la zapata podr\u00eda caerse, se recomienda siempre moler la pintura, escamas o superficies con \u00f3xidos para que se asegure el contacto entre zapata y cadena.<\/li>\n<\/ul>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"CADENAS_RESBALANDOSE_DE_LOS_PINONES\"><\/span>CADENAS RESBALANDOSE DE LOS PI\u00d1ONES<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>El desgaste excesivo de los pi\u00f1ones podr\u00eda provocar que las cadenas se resbalen sobre los pi\u00f1ones.<\/li>\n<li>En el caso de que las cadenas y los pi\u00f1ones sean nuevos, el problema podr\u00eda ser provocado porque el resorte del ajustador de la oruga est\u00e9 en mal estado, lo que genera que se retraiga y la tensi\u00f3n no sea la adecuada, es decir est\u00e9 floja.<\/li>\n<li>En algunos casos la rueda dentada solo encajar\u00e1 en una direcci\u00f3n, podr\u00eda estar situada incorrectamente.<\/li>\n<li>Las cadenas pueden tener un paso incorrecto con los pi\u00f1ones o viceversa.<\/li>\n<\/ul>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"PROBLEMAS_COMUNES_EN_TRENES_DE_RODAJES\"><\/span>PROBLEMAS COMUNES EN TRENES DE RODAJES<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"PISTAS_DE_ENLACES\"><\/span><a href=\"https:\/\/www.yutaniglobal.com\/es\/ensamble-yutani-track-link\/\" title=\"Conjunto de enlace de pista\">PISTAS DE ENLACES<\/a><span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>En condiciones normales el desgaste que se produce en los eslabones de pista se encuentra en la superficie que tiene contacto con los rodillos <br>y ruedas locas.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Wear-of-track-chain.png\u00bb title_text=\u00bbWear-of-track-chain\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Existen diversos casos que generan problemas en los elementos, los cuales se mencionan a continuaci\u00f3n:<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"EXCESIVO_DESGASTE_DEL_RIEL_LATERAL\"><\/span>EXCESIVO DESGASTE DEL RIEL LATERAL<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Existen diversos tipos factores que ocasionan desgastes generales, entre las cuales se encuentran las condiciones operativas, terrenos desiguales o giros bruscos, este tipo de desgaste es m\u00e1s com\u00fan cuando existe una desalineaci\u00f3n en la pista, un serpenteo excesivo de la cadena o que las cadenas se encuentren muy desgastadas.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Wear-of-side-rail.png\u00bb title_text=\u00bbWear-of-side-rail\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"INDENTACIONES_EN_SUPERFICIE_INTERNA_DE_CARRIL\"><\/span>INDENTACIONES EN SUPERFICIE INTERNA DE CARRIL<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Este problema tiene varias causas, entre las cuales destacan la inclinaci\u00f3n del terreno, desalineaci\u00f3n del pi\u00f1os y cadenas dobladas, lo que provoca que los diente de la rueda dentada se choquen y rocen con el interior del enlace. Podr\u00eda solucionar este problema verificando la alineaci\u00f3n y ajustando la tensi\u00f3n de la cadena.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Rail-surface.png\u00bb title_text=\u00bbRail-surface\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESGASTE_LATERAL_DEL_PIN_MAESTRO\"><\/span>DESGASTE LATERAL DEL PIN MAESTRO<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Se genera debido al contacto con la brida externa de los rodillos, en el caso que ocurra antes de que el eslab\u00f3n est\u00e9 desgastado al 100%, lo que significa que los rodillos sobrepasaron su vida \u00fatil y requieren cambio.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Pin-sid-wear.png\u00bb title_text=\u00bbPin-sid-wear\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESGASTE_FACIAL_EXCESIVO\"><\/span>DESGASTE FACIAL EXCESIVO<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<ul>\n<li>Se produce por el serpenteo de los eslabones o las condiciones de operaci\u00f3n, para poder reducir o retardar este tipo de desgaste se recomienda usar protectores de cadenas o emplear <a href=\"https:\/\/www.yutaniglobal.com\/es\/cadena-de-la-pista-de-bulldozer-yutani\/\" title=\"cadenas lubricadas\">cadenas lubricadas.<\/a><\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Facial-wear.png\u00bb title_text=\u00bbFacial-wear\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"ESQUINAS_DE_RIEL_GOLPEADAS\"><\/span>ESQUINAS DE RIEL GOLPEADAS<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Entre las distintas causas se destacan las condiciones de funcionamiento como el tipo de trabajo a realizar, la velocidad de ejecuci\u00f3n, peso y potencia de la m\u00e1quina, adem\u00e1s de una causa en particular que se genera a parir de las cargas de choque transmitidas por los rodillos a los enlaces. Una soluci\u00f3n posible podr\u00eda ser modificar la tensi\u00f3n de la cadena y\/o reducir el tama\u00f1o de la zapata.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Rail-corners.png\u00bb title_text=\u00bbRail-corners\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"GRIETAS_O_ROTURAS_EN_LAS_ZONAS_CON_MAYORES_ESFUERZOS\"><\/span>GRIETAS O ROTURAS EN LAS ZONAS CON MAYORES ESFUERZOS<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>En la mayor\u00eda de los casos las roturas son generadas por los esfuerzos de torsi\u00f3n que es trasmitido a la estructura del enlace en las ocasiones que la m\u00e1quina se encuentra operando en condiciones de alto impacto, se puede controlar esta falla empleando zapatas m\u00e1s estrechas y reajustando la tensi\u00f3n de la cadena.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Breaks.png\u00bb title_text=\u00bbBreaks\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DEFORMACION_DEL_CASQUILLO_ANTERIOR_Y_PASADOR\"><\/span>DEFORMACI\u00d3N DEL CASQUILLO ANTERIOR Y PASADOR<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Este problema puede ocasionarse en 2 ocasiones: al momento del montaje o desmontaje de la cadena o en operaci\u00f3n causado por los esfuerzos de flexi\u00f3n en los pasadores y casquillos, este problema puede ser mejorado si se coloca una zapata m\u00e1s peque\u00f1a.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/wear-of-bushinng.png\u00bb title_text=\u00bbwear-of-bushinng\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"PASADORES_Y_ARBUSTOS_DEL_TIPO_RELLENO_DE_GRASA\"><\/span>PASADORES Y ARBUSTOS DEL TIPO RELLENO DE GRASA<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>El estiramiento de la cadena sirve para medir el desgaste interno que sufren los pasadores y casquillos de cadenas engrasadas y selladas, se emplea midiendo los pasadores entre centros de un conjunto de 4-5 eslabones y se realiza una comparaci\u00f3n con las nuevas especificaciones de la cadena.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Wear-of-pins-and-bushs.png\u00bb title_text=\u00bbWear-of-pins-and-bushs\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESGASTE_DEL_EXTREMO_FINAL_DEL_PASADOR\"><\/span>DESGASTE DEL EXTREMO FINAL DEL PASADOR<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Existen factores bastante obvios que pueden ocasionas este tipo de problema, entre los cuales destacan la operaci\u00f3n en laderas o en terrenos irregulares este problema es generado por la tensi\u00f3n incorrecta de las cadenas y por un desgaste excesivo de los rodillos. En el caso de que la cadena no est\u00e9 limitada se recomienda reajustar la tensi\u00f3n y girar los rodillos.<\/li>\n<li>En el caso de que este tipo de desgaste aparezca inmediatamente luego de la instalaci\u00f3n de un tren de rodaje nuevo se debe verificar la posici\u00f3n de los protectores de orugas no se encuentre tan cercana a la cadena.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Wear-of-pin-final.png\u00bb title_text=\u00bbWear-of-pin-final\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"PASADORES_SUELTOS\"><\/span>PASADORES SUELTOS<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Se debe descartar que la falla se produzca por un montaje o desmontaje incorrecto, en el caso de descartarse este caso el problema podr\u00eda ser provocado por el esfuerzo de flexi\u00f3n cuando el equipo se encuentre realizando un trabajo pesado. Este problema se soluciona reemplazando las zapatas m\u00e1s desgastadas o reemplaz\u00e1ndolas, adem\u00e1s de revisar el apriete de los pernos.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Loose-pins.png\u00bb title_text=\u00bbLoose-pins\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"ROTURAS_DE_PASADOR\"><\/span>ROTURAS DE PASADOR<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>La rotura se produce cuando existen golpes extremadamente fuertes o cargas est\u00e1ticas elevadas principalmente suceden cuando el terreno de trabajo es rocoso, otra ocasi\u00f3n es cuando el material se acumula en la rueda dentado ocasionando que la cadena de la pista sufra una tensi\u00f3n extremadamente elevada. La soluci\u00f3n viable es proteger la cadena de oruga y la rueda dentada empleando zapatas con agujeros.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Pin-breaks.png\u00bb title_text=\u00bbPin-breaks\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>El desgaste com\u00fan de los casquillos se produce en la superficie externa, este se comienza a desgastar progresivamente de manera uniforme, y debe medirse en el centro del \u00e1rea de desgaste.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Out-surface-bush-wear.png\u00bb title_text=\u00bbOut-surface-bush-wear\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Existe diversas maneras de medir el desgaste exterior, la m\u00e1s com\u00fan es evaluar la distancia desde la parte inferior de la zapata hasta el centro del \u00e1rea de desgaste en el buje, se emplea usualmente un medidor de profundidad o tambi\u00e9n se puede emplear una herramienta indicadora de desgaste por ultrasonido.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/measure-outer-wear.png\u00bb title_text=\u00bbmeasure-outer-wear\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESCASCARAMIENTO_DEL_PASADOR\"><\/span>DESCASCARAMIENTO DEL PASADOR<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>El desconchado se produce debido a grandes esfuerzos de flexi\u00f3n especialmente en trabajos de condiciones pesadas.<\/li>\n<li>Adem\u00e1s, las condiciones de trabajo de la m\u00e1quina este tipo de problema puede ser generado por una tensi\u00f3n extremadamente grande en las cadenas que se produce por una acumulaci\u00f3n de material, una forma de solucionar este problema es reajustando la cadena y protegi\u00e9ndola de la acumulaci\u00f3n de material, en especial rocas, entre la cadena y el pi\u00f1\u00f3n.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/PIN-spalling.png\u00bb title_text=\u00bbPIN-spalling\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"RODILLOS_INFERIORES_DE_LA_PISTA\"><\/span>RODILLOS INFERIORES DE LA PISTA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>En este secci\u00f3n lo m\u00e1s importante es conocer el desgaste de la banda de rodadura del rodillo, la cual se mide en funci\u00f3n del di\u00e1metro.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Lower-track-roller.png\u00bb title_text=\u00bbLower-track-roller\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>La herramienta que se debe emplear es una pinza exterior, la medida que se requiere es la del menor di\u00e1metro de las banas de rodadura del rodillo, debido a que justamente la de menor di\u00e1metro ser\u00e1 la que presente el mayor desgaste, sin embargo, esta medici\u00f3n es bastante dif\u00edcil de realizar, por lo cual es suficiente medir el rodillo delantero y el trasero debido a que el desgaste se produce entre estos 2 puntos por el balanceo propio de la m\u00e1quina cuando se encuentra en operaci\u00f3n.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Measure-lower-track-roller.png\u00bb title_text=\u00bbMeasure-lower-track-roller\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESGASTE_EXCESIVO_DE_LA_BRIDA_LATERAL\"><\/span>DESGASTE EXCESIVO DE LA BRIDA LATERAL<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<ul>\n<li>Este tipo de desgaste es com\u00fan debido a las condiciones de trabajo del equipo y adem\u00e1s tambi\u00e9n podr\u00eda producirse por una desalineaci\u00f3n o tambi\u00e9n por que la tensi\u00f3n de la cadena no es la correcta, principalmente en estos casos es debido a que la cadena est\u00e1 holgada.<\/li>\n<li>Tiene que considerarse que los rodillos de doble pesta\u00f1a tienen una vida \u00fatil mucho mayor, y adem\u00e1s ser muy cuidadoso con la secuencia de los rodillos de doble y simple pesta\u00f1a.<\/li>\n<li>Como recomendaci\u00f3n si se desea una vida \u00fatil mayor en las mismas condiciones de trabajo se podr\u00edan instalar m\u00e1s rodillos de doble pesta\u00f1a.<\/li>\n<\/ul>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/wear-of-the-side-flange.png\u00bb title_text=\u00bbwear-of-the-side-flange\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DEFORMACION_DE_LA_BRIDA_SUPERIOR\"><\/span>DEFORMACI\u00d3N DE LA BRIDA SUPERIOR<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Se produce por el contacto del pasador o se debe por el deslizamiento de las cadenas sobre las bridas, debido a un movimiento tipo serpenteo de la cadena. En el caso de que la cadena no se encuentre totalmente gastada, ajuste la tensi\u00f3n, realice un alineamiento de rodillos y vuelva a colocar los rieles de gu\u00eda se la pista.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h5><span class=\"ez-toc-section\" id=\"ZAPATAS-2\"><\/span>ZAPATAS<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>En este elemento el desgaste m\u00e1s relevante es la altura relativa de la orejeta de la garra desde la parte superior <br>del zapato. Se emplea un medidor de profundidad<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Track-shoe.png\u00bb title_text=\u00bbTrack-shoe\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"DESGASTE_ACELERADO_DE_SUPERFICIES_SUPERPUESTAS\"><\/span>DESGASTE ACELERADO DE SUPERFICIES SUPERPUESTAS<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Esto normalmente es causado por una cadena que se encuentra desgastada y se resuelve ajustando, generalmente apret\u00e1ndolas cadenas, o reemplaz\u00e1ndolas.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/Wear-of-overlapping-surface.png\u00bb title_text=\u00bbWear-of-overlapping-surface\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<h6><span class=\"ez-toc-section\" id=\"AGUJEROS_PARA_PERNOS_AMPLIADOS\"><\/span>AGUJEROS PARA PERNOS AMPLIADOS<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb]<p>Se produce por el movimiento que existe entre la zapata y la cadena, su causa puede ser que los pernos est\u00e9n sueltos o al movimiento de la m\u00e1quina. Existen varias soluciones entre las cuales destacan un tama\u00f1o reducido de zapata o unas zapatas con menos penetraci\u00f3n, un control del par de torsi\u00f3n del perno servir\u00e1.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/holes-for-bolts.png\u00bb title_text=\u00bbholes-for-bolts\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.9.4&#8243; _module_preset=\u00bbdefault\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00d3MO REMPLAZAR LAS PISTAS DE UNA BULLDOZER?El reemplazo de la cadena de cadenas es importante. Para reemplazar alg\u00fan elemento del tren de rodaje es necesario retirar la oruga, incluso en el caso que se requiera remplazarlo, o cuando se realicen mantenimientos y reparaciones en el tren de rodaje. Para poder extraer las pistas se debe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":232029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-232336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-relacionados-con-excavadoras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA YUTANI<\/title>\n<meta name=\"description\" content=\"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA\" \/>\n<meta property=\"og:description\" content=\"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/\" \/>\n<meta property=\"og:site_name\" content=\"YUTANI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/YutaniExcavatorParts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/YutaniExcavatorParts\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-10T17:49:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-10T17:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\" \/>\n<meta name=\"author\" content=\"YUTANI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA\" \/>\n<meta name=\"twitter:description\" content=\"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"YUTANI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/\"},\"author\":{\"name\":\"YUTANI\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/be1169e3779e615f288751870559d677\"},\"headline\":\"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA\",\"datePublished\":\"2021-05-10T17:49:19+00:00\",\"dateModified\":\"2021-05-10T17:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/\"},\"wordCount\":3979,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\",\"articleSection\":[\"Consejos relacionados con excavadoras\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/\",\"name\":\"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA YUTANI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\",\"datePublished\":\"2021-05-10T17:49:19+00:00\",\"dateModified\":\"2021-05-10T17:50:32+00:00\",\"description\":\"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\",\"contentUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png\",\"width\":700,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\",\"name\":\"YUTANI\",\"description\":\"Your Reliable Excavator Undercarriage Parts Supplier Partner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\",\"name\":\"YUTANI\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.ico\",\"contentUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.ico\",\"width\":16,\"height\":16,\"caption\":\"YUTANI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/YutaniExcavatorParts\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yutanichina\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/be1169e3779e615f288751870559d677\",\"name\":\"YUTANI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"caption\":\"YUTANI\"},\"description\":\"YUTANI focuses on the excavator track chain industry. It is the designated supplier of many excavator original equipment manufacturer.\",\"sameAs\":[\"https:\\\/\\\/www.yutaniglobal.com\",\"https:\\\/\\\/www.facebook.com\\\/YutaniExcavatorParts\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yutanichina\\\/\"],\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/author\\\/yutani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA YUTANI","description":"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/","og_locale":"es_ES","og_type":"article","og_title":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA","og_description":"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.","og_url":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/","og_site_name":"YUTANI","article_publisher":"https:\/\/www.facebook.com\/YutaniExcavatorParts","article_author":"https:\/\/www.facebook.com\/YutaniExcavatorParts","article_published_time":"2021-05-10T17:49:19+00:00","article_modified_time":"2021-05-10T17:50:32+00:00","og_image":[{"url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","type":"","width":"","height":""}],"author":"YUTANI","twitter_card":"summary_large_image","twitter_title":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA","twitter_description":"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.","twitter_image":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","twitter_misc":{"Escrito por":"YUTANI","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#article","isPartOf":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/"},"author":{"name":"YUTANI","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/person\/be1169e3779e615f288751870559d677"},"headline":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA","datePublished":"2021-05-10T17:49:19+00:00","dateModified":"2021-05-10T17:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/"},"wordCount":3979,"publisher":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","articleSection":["Consejos relacionados con excavadoras"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/","url":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/","name":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA YUTANI","isPartOf":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#primaryimage"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","datePublished":"2021-05-10T17:49:19+00:00","dateModified":"2021-05-10T17:50:32+00:00","description":"El reemplazo de la cadena de cadenas es importante. \u00bfD\u00f3nde necesitas comprobar y c\u00f3mo se ve? YUTANI proporciona la calidad de las cadenas de orugas.","breadcrumb":{"@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#primaryimage","url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","contentUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/04\/TRACK-CHAIN-REPLACEMENT-USES-TIPS-AND-COMMON-PROBLEMS.png","width":700,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/www.yutaniglobal.com\/es\/consejos-para-el-reemplazo-de-la-cadena-de-oruga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.yutaniglobal.com\/es\/"},{"@type":"ListItem","position":2,"name":"CONSEJOS PARA EL REEMPLAZO DE LA CADENA DE ORUGA"}]},{"@type":"WebSite","@id":"https:\/\/www.yutaniglobal.com\/es\/#website","url":"https:\/\/www.yutaniglobal.com\/es\/","name":"YUTANI","description":"Your Reliable Excavator Undercarriage Parts Supplier Partner","publisher":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yutaniglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yutaniglobal.com\/es\/#organization","name":"YUTANI","url":"https:\/\/www.yutaniglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2020\/08\/favicon.ico","contentUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2020\/08\/favicon.ico","width":16,"height":16,"caption":"YUTANI"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/YutaniExcavatorParts","https:\/\/www.linkedin.com\/company\/yutanichina\/"]},{"@type":"Person","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/person\/be1169e3779e615f288751870559d677","name":"YUTANI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","caption":"YUTANI"},"description":"YUTANI focuses on the excavator track chain industry. It is the designated supplier of many excavator original equipment manufacturer.","sameAs":["https:\/\/www.yutaniglobal.com","https:\/\/www.facebook.com\/YutaniExcavatorParts","https:\/\/www.linkedin.com\/company\/yutanichina\/"],"url":"https:\/\/www.yutaniglobal.com\/es\/author\/yutani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts\/232336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/comments?post=232336"}],"version-history":[{"count":0,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts\/232336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/media\/232029"}],"wp:attachment":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/media?parent=232336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/categories?post=232336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/tags?post=232336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}