{"id":232439,"date":"2022-06-22T05:54:53","date_gmt":"2022-06-22T05:54:53","guid":{"rendered":"https:\/\/www.yutaniglobal.com\/que-es-una-excavadora-anfibia\/"},"modified":"2022-06-22T05:54:57","modified_gmt":"2022-06-22T05:54:57","slug":"que-es-una-excavadora-anfibia","status":"publish","type":"post","link":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/","title":{"rendered":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a977d9b94c2b\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a977d9b94c2b\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#CARACTERISTICAS_DE_LA_EXCAVADORA_ANFIBIA\" >CARACTER\u00cdSTICAS DE LA EXCAVADORA ANFIBIA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#APLICACIONES_INDUSTRIALES\" >APLICACIONES INDUSTRIALES<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#CONSTRUIDO_PARA_FUNCIONAR_EN_CUALQUIER_SITUACION\" >CONSTRUIDO PARA FUNCIONAR EN CUALQUIER SITUACI\u00d3N<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#DRAGADO_DE_EXCAVACION_Y_DRAGADO_DE_SUCCION\" >DRAGADO DE EXCAVACI\u00d3N Y DRAGADO DE SUCCI\u00d3N<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#DRAGADO_DE_CANALES_DE_ENTRADA_Y_EMBALSE_EN_CENTRAL_HIDROELECTRICA\" >DRAGADO DE CANALES DE ENTRADA Y EMBALSE EN CENTRAL HIDROEL\u00c9CTRICA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#CORTAR_LA_VEGETACION_ACUATICA\" >CORTAR LA VEGETACI\u00d3N ACU\u00c1TICA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#LIMPIEZA\" >LIMPIEZA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#INDUSTRIA_MINERA\" >INDUSTRIA MINERA<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#TREN\" >TREN<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#SIMILITUDES_Y_DIFERENCIAS_CON_UNA_EXCAVADORA_CONVENCIONAL\" >SIMILITUDES Y DIFERENCIAS CON UNA EXCAVADORA CONVENCIONAL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#ELEMENTOS_DE_SOPORTE_OPCIONALES\" >ELEMENTOS DE SOPORTE OPCIONALES<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#1_SISTEMA_SPUD_OPCIONAL\" >1) SISTEMA SPUD OPCIONAL:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#2_ACCESORIOS_PARA_EXCAVADORAS_CUCHARONES_PLUMAS_EXTENDIDAS\" >2) ACCESORIOS PARA EXCAVADORAS (CUCHARONES, PLUMAS EXTENDIDAS)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#1_PLUMA_EXTENDIDA\" >1. PLUMA EXTENDIDA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#2_PONTON_ANFIBIO\" >2. PONT\u00d3N ANFIBIO<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#3_CADENAS_DE_ORUGAS\" >3. CADENAS DE ORUGAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#4_DISPOSITIVO_TENSOR_DE_CADENA\" >4. DISPOSITIVO TENSOR DE CADENA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#5_PONTON_RETRACTIL\" >5. PONT\u00d3N RETR\u00c1CTIL<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb][et_pb_row _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Una excavadora anfibia es un tipo de excavadora que cuenta con un equipo de pontones sellado que le permite realizar trabajos de dragado mientras flota en aguas poco profundas. Los pontones est\u00e1n construidos con acero de alta resistencia a la tracci\u00f3n, debido a las condiciones de trabajo en las que se encuentran, son resistentes a la corrosi\u00f3n y capaces de trabajar en condiciones de alta salinidad como en el caso de trabajar con agua de mar. Esto garantiza que la excavadora pueda funcionar incluso en condiciones extremas. Es un equipo que est\u00e1 dise\u00f1ado espec\u00edficamente para maniobrar en \u00e1reas pantanosas como humedales y terrenos blandos, as\u00ed como para flotar en el agua. Estas excavadoras son totalmente autopropulsadas utilizando un sistema hidr\u00e1ulico de gu\u00eda de accionamiento directo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El principio f\u00edsico que hace posible la excavadora anfibia radica en los pontones herm\u00e9ticamente sellados, que est\u00e1n dise\u00f1ados bajo el principio de Arqu\u00edmedes. Junto con su gran huella, esto crea una presi\u00f3n de suelo realmente baja. La m\u00e1quina es capaz de operar dentro de \u00e1reas secas, blandas y pantanosas con poco o ning\u00fan riesgo de quedar atrapada en el barro.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Los trenes de rodaje son considerados como una de las principales innovaciones en el \u00e1rea de la industria de la construcci\u00f3n. Estas excavadoras son capaces de operar en los duros humedales que son comunes en todo el mundo, especialmente en Am\u00e9rica del Norte y Europa. Com\u00fanmente, los ingenieros se limitaban a realizar operaciones en tierra firme, por lo que en estas condiciones tendr\u00edan que descubrir c\u00f3mo generar tierra s\u00f3lida para estas m\u00e1quinas mediante la construcci\u00f3n de carreteras o la introducci\u00f3n de barcazas a trav\u00e9s de canales. Debido a que se requiri\u00f3 reducir estos costos generales relacionados con los humedales, los ingenieros desarrollaron el tren de aterrizaje anfibio. El tren de rodaje anfibio podr\u00eda instalarse en excavadoras y otros equipos de trabajo pesados, adherirse al tren de rodaje le da flotabilidad y la capacidad de trabajar en ambientes h\u00famedos sin la necesidad de construir una base s\u00f3lida para transportarlo.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/CAT-Amphibious-excavator.png\u00bb _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbCAT-Excavadora anfibia\u00bb align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Las modificaciones de equipos anfibios son ideales para transportar de manera segura a los trabajadores y equipos a los sitios de trabajo en terrenos que son demasiado blandos para caminar y demasiado densos para flotar. Antes del uso de excavadoras anfibias, el desarrollo de proyectos industriales requer\u00eda que los trabajadores construyeran canales, carreteras o plataformas antes de operar equipos pesados en pantanos y marismas. Este punto extra para adaptar los equipos a las condiciones de trabajo no solo era muy extenso y dif\u00edcil, sino que tambi\u00e9n era muy costoso y realmente da\u00f1ino para el medio ambiente local porque generalmente eran humedales y pantanos con una ecolog\u00eda fr\u00e1gil. Por otro lado, estos caminos y canales eran necesarios para soportar cargas de maquinaria grande en terrenos blandos o h\u00famedos, por lo que a veces no eran trabajos innecesarios, pero eran muy limitantes. Utilizando excavadoras anfibias el procedimiento es mucho m\u00e1s simple, se pueden eliminar muchos pasos conduciendo la maquinaria directamente al sitio de trabajo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"CARACTERISTICAS_DE_LA_EXCAVADORA_ANFIBIA\"><\/span>CARACTER\u00cdSTICAS DE LA EXCAVADORA ANFIBIA<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>La caracter\u00edstica m\u00e1s notable del tren de aterrizaje anfibio que distingue al equipo de una excavadora com\u00fan es el hecho de que puede proporcionar flotabilidad a trav\u00e9s de pontones herm\u00e9ticamente sellados. Los pontones, que son extensibles, permiten que la excavadora flote en el agua con la opci\u00f3n de montar palets verticales si no hay un terreno desigual diferente en el que exista riesgo de operaci\u00f3n. El movimiento se realiza mediante la cadena de cadenas que utiliza un sistema de accionamiento hidr\u00e1ulico multis\u00edncrono. La cadena de orugas se utiliza para soportar la flotaci\u00f3n, proporciona un mayor nivel de eficiencia de tracci\u00f3n y estabilidad en un rango m\u00e1s amplio para todo tipo de operaciones, es decir, de acuerdo con las condiciones del terreno. La excavadora se puede adaptar con diferentes accesorios para cada aplicaci\u00f3n. Debido a esta capacidad, es posible que los operadores realicen una amplia gama de tareas para diferentes aplicaciones industriales.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"APLICACIONES_INDUSTRIALES\"><\/span>APLICACIONES INDUSTRIALES<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Por sentido com\u00fan se sabe que los equipos anfibios ser\u00e1n \u00fatiles para ser utilizados alrededor de humedales y pantanos, sin embargo, existen muchos otros escenarios y condiciones en las que el uso de equipos anfibios permite que el trabajo sea m\u00e1s f\u00e1cil. Los proyectos que se realizan alrededor de costas oce\u00e1nicas, cauces fluviales y especialmente en zonas de recientes inundaciones en las que utilizar una excavadora anfibia es la mejor opci\u00f3n para ahorrar costes y optimizar el tiempo de funcionamiento. Las excavadoras anfibias pueden funcionar de manera eficiente en una amplia gama de aplicaciones, incluidos los esfuerzos de recuperaci\u00f3n de inundaciones y desastres, el dragado, la remediaci\u00f3n ambiental y varios proyectos de construcci\u00f3n, como tuber\u00edas, diques o tendidos de carreteras.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El uso de excavadoras anfibias tambi\u00e9n es la mejor opci\u00f3n para el dragado ambiental, por lo que su uso no solo se limita al \u00e1rea de construcci\u00f3n. Las tareas de dragado a veces se ven obstaculizadas por las profundidades de las aguas poco profundas porque las excavadoras pueden atascarse f\u00e1cilmente o tener un alcance limitado. Debido a la versatilidad de los equipos anfibios que pueden flotar en el agua y se pueden manejar en tierra, el operador no tiene que preocuparse por operar demasiado cerca o demasiado lejos del borde del agua. Las v\u00edas anchas y un peso conveniente para la operaci\u00f3n hacen que la presi\u00f3n sobre el suelo no sea excesiva, por otro lado, un equipo mucho m\u00e1s pesado provoca surcos profundos. Adem\u00e1s, la capacidad de montar una bomba de dragado directamente en la excavadora le da la capacidad de tener tasas \u00f3ptimas de movimiento y producci\u00f3n.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"CONSTRUIDO_PARA_FUNCIONAR_EN_CUALQUIER_SITUACION\"><\/span>CONSTRUIDO PARA FUNCIONAR EN CUALQUIER SITUACI\u00d3N<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator-with-long-boom.png\u00bb _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbExcavadora anfibia con pluma larga\u00bb align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"DRAGADO_DE_EXCAVACION_Y_DRAGADO_DE_SUCCION\"><\/span>DRAGADO DE EXCAVACI\u00d3N Y DRAGADO DE SUCCI\u00d3N<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Todos los tipos de dragado de excavaci\u00f3n en \u00e1reas de aguas poco profundas, que se consideran de hasta 9 metros, deben realizarse con una excavadora anfibia. La retirada de barro o piedras, la transformaci\u00f3n de espacios de almac\u00e9n o la limpieza de estanques de residuos industriales son las aplicaciones m\u00e1s comunes, generalmente son m\u00e1s utilizadas en aspectos de control ambiental.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"DRAGADO_DE_CANALES_DE_ENTRADA_Y_EMBALSE_EN_CENTRAL_HIDROELECTRICA\"><\/span>DRAGADO DE CANALES DE ENTRADA Y EMBALSE EN CENTRAL HIDROEL\u00c9CTRICA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Los sedimentos que se acumulan en el fondo de los canales de entrada y el embalse de la presa de la central hidroel\u00e9ctrica se pueden dragar para mantener un flujo suficiente para las operaciones de la planta, y especialmente para cuidar el equipo interno de las centrales hidroel\u00e9ctricas, es un tipo de mantenimiento preventivo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"CORTAR_LA_VEGETACION_ACUATICA\"><\/span>CORTAR LA VEGETACI\u00d3N ACU\u00c1TICA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>La vegetaci\u00f3n acu\u00e1tica que crece en el fondo del r\u00edo o lago se puede eliminar con una excavadora anfibia y un rastrillo. Tambi\u00e9n es posible eliminar las ra\u00edces de la planta y as\u00ed evitar que las plantas vuelvan a crecer. Si es necesario, se pueden usar herramientas hidr\u00e1ulicas especiales para cortar. Como complemento, se puede utilizar una cinta transportadora y un cortador, para algunos casos, especialmente para plantas invasoras.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"LIMPIEZA\"><\/span>LIMPIEZA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Es f\u00e1cil operar una excavadora anfibia en canales y otras v\u00edas fluviales estrechas. La basura, las hojas y ramas de los \u00e1rboles, y el exceso de sedimentos que se acumulan en el fondo del canal se pueden eliminar mediante dragado.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"INDUSTRIA_MINERA\"><\/span>INDUSTRIA MINERA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El uso de una excavadora anfibia puede ser \u00fatil en muchas etapas de las minas a cielo abierto. A menudo se utiliza, por ejemplo, para ayudar a las bombas de agua y otros trabajos de drenaje y presas.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"TREN\"><\/span>TREN<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El tren de rodaje es una parte esencial para comprender el funcionamiento de la excavadora anfibia. Es una estructura de soporte de m\u00faltiples equipos, el tren de aterrizaje hidr\u00e1ulico anfibio tiene que desarrollar varias funciones de soporte. En el caso de que est\u00e9 equipado con una zanjadora, servir\u00e1 como una pieza integral de equipo en el control de insectos, especialmente mosquitos, as\u00ed como en la excavaci\u00f3n de zanjas para la colocaci\u00f3n de tuber\u00edas, por ejemplo. Cuando se utiliza el tren de rodaje hidr\u00e1ulico anfibio, puede atravesar terrenos pantanosos y h\u00famedos con inundaciones parciales, terreno que complicar\u00eda el funcionamiento de una excavadora tradicional. Del mismo modo, en el caso de que est\u00e9 equipada con una gr\u00faa grande, la gr\u00faa tiene la capacidad de operar en una variedad de terrenos, este aspecto es ideal para trabajos de construcci\u00f3n que tienen varios tipos de pisos de trabajo.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator-undercarriage-Pontoon.png\u00bb _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbAnfibia-excavadora-tren de rodaje-Pont\u00f3n\u00bb align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"SIMILITUDES_Y_DIFERENCIAS_CON_UNA_EXCAVADORA_CONVENCIONAL\"><\/span>SIMILITUDES Y DIFERENCIAS CON UNA EXCAVADORA CONVENCIONAL<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Con respecto al plano estructural, las excavadoras anfibias tienen un dise\u00f1o muy similar al de una excavadora convencional, pueden proporcionar giros de 360 grados manteniendo fijo el tren de rodaje, tienen brazo, pluma, cabina de operaci\u00f3n, contrapeso, etc. La diferencia concreta radica en el tren de rodaje, que en el caso de ser una excavadora anfibia est\u00e1 equipado con cascos o pontones que se asemejan a los de una embarcaci\u00f3n para maximizar la tracci\u00f3n y proporcionar flotabilidad al equipo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Existen varios tipos de excavadoras anfibias que se clasifican seg\u00fan su forma de desplazamiento:<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>1.- El equipo utilizado para su uso en aguas poco profundas tiende a moverse de forma convencional utilizando \u00fanicamente el tren de rodaje con pontones, lo que reduce la presi\u00f3n sobre el suelo debido a la anchura de las v\u00edas y su mayor superficie de contacto, maximizando la tracci\u00f3n del equipo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>2.- Utilizados para su uso en aguas profundas: Se pueden mover apoyados por el brazo y la pluma de la excavadora. Para minimizar el riesgo de vuelco durante la operaci\u00f3n, es com\u00fan agregar generalmente un conjunto adicional de pontones laterales, que incluyen los llamados \u00abspuds\u00bb o pilares de retenci\u00f3n, que se encargan de mantener el equipo en una zona. de trabajo espec\u00edfico aportando estabilidad a los equipos porque mejoran la penetraci\u00f3n al suelo.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>3.-Utilizados para su uso en aguas profundas soportadas por h\u00e9lices: Su dise\u00f1o es como el de los equipos para aguas profundas, est\u00e1n equipados con un juego adicional de pontones, sin embargo, se implementa un mecanismo de h\u00e9lice en los cascos laterales que ser\u00e1 el encargado de soportar el movimiento en comparaci\u00f3n con el apoyado por el brazo y la pluma.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h5><span class=\"ez-toc-section\" id=\"ELEMENTOS_DE_SOPORTE_OPCIONALES\"><\/span>ELEMENTOS DE SOPORTE OPCIONALES<span class=\"ez-toc-section-end\"><\/span><\/h5>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Existen varios accesorios que potencian las capacidades de las excavadoras anfibias, entre los que destacan las siguientes opciones:<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"1_SISTEMA_SPUD_OPCIONAL\"><\/span>1) SISTEMA SPUD OPCIONAL:<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Spuds hidr\u00e1ulicos laterales adicionales disponibles que se utilizan para mejorar la estabilidad del equipo en el \u00e1rea de trabajo, que se requieren si el calado de agua de la condici\u00f3n de trabajo del sitio es de 2 a 3.5 metros.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Spud, al igual que su mecanismo hidr\u00e1ulico integrado en los pontones sellados, debe ensamblarse a ambos lados de la excavadora anfibia. Las patas de la punta est\u00e1n controladas por la potencia hidr\u00e1ulica para acostarse y posicionarse. La longitud de las patas de la llana est\u00e1 determinada por la profundidad del agua en el \u00e1rea de trabajo. Antes de que la excavadora comience su etapa de producci\u00f3n, debe levantar las patas de la punta y luego encender el mecanismo hidr\u00e1ulico para insertar las patas en el barro submarino. El sistema Spud es un gran accesorio porque mejora en gran medida la estabilidad operativa submarina de la m\u00e1quina.<\/p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator-with-spud.png\u00bb _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb title_text=\u00bbExcavadora anfibia con spud\u00bb align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"2_ACCESORIOS_PARA_EXCAVADORAS_CUCHARONES_PLUMAS_EXTENDIDAS\"><\/span>2) ACCESORIOS PARA EXCAVADORAS (CUCHARONES, PLUMAS EXTENDIDAS)<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"1_PLUMA_EXTENDIDA\"><\/span>1. PLUMA EXTENDIDA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>La pluma extendida est\u00e1 dise\u00f1ada para satisfacer la demanda de grandes proyectos de construcci\u00f3n. El radio de operaci\u00f3n, la altura y el ancho de la excavaci\u00f3n cuando se utiliza una pluma extendida aumentan el l\u00edmite de operaci\u00f3n que sirve para cumplir con condiciones de trabajo espec\u00edficas. Principalmente el uso de la pluma extendida no representa ning\u00fan riesgo para el equipo, podemos garantizar la estabilidad y seguridad del trabajo de toda la excavadora mediante el uso de una pluma extendida.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"2_PONTON_ANFIBIO\"><\/span>2. PONT\u00d3N ANFIBIO<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El pont\u00f3n anfibio est\u00e1 hecho de acero A36, que es un material especial para barcos, y tambi\u00e9n de placa de aluminio de alta resistencia. Los pontones se granallan para asegurarse de que la superficie est\u00e9 completamente limpia, libre de contaminantes y \u00f3xidos. Adem\u00e1s, este proceso presenta al acero una textura superficial que proporciona una excelente adherencia de la primera capa de pintura, facilitando el proceso de pintura. El dise\u00f1o responsable de la estructura y el an\u00e1lisis de elementos finitos de las pruebas destructivas en el sitio de trabajo garantizan en gran medida que los pontones anfibios tengan la capacidad de carga y la seguridad adecuadas.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"3_CADENAS_DE_ORUGAS\"><\/span>3. <a href=\"https:\/\/www.yutaniglobal.com\/es\/cadena-de-oruga-excavadora-yutani\/\" target=\"_blank\" rel=\"noopener\" title=\"Cadenas de seguimiento\">CADENAS DE ORUGAS<\/a><span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Las cadenas de orugas y rodillos de los pontones anfibios est\u00e1n hechos de 40Cr, mientras que las mangas medianas est\u00e1n hechas de un material s\u00faper resistente al desgaste 20CrMnTi, debido a esto las mangas tienen una alta vida \u00fatil. El dise\u00f1o especial de tres pistas disminuir\u00e1 la tensi\u00f3n en cada pista y promediar\u00e1 la tensi\u00f3n en las zapatas de la pista para que la pista sea m\u00e1s eficiente. La principal ventaja es que toda la m\u00e1quina tendr\u00e1 la capacidad de continuar movi\u00e9ndose a la estaci\u00f3n de reparaci\u00f3n despu\u00e9s de que se rompa una de las cadenas, lo que contribuye significativamente a reducir los costos de reparaci\u00f3n y mantenimiento durante el trabajo. Adem\u00e1s, todas las <a href=\"https:\/\/www.yutaniglobal.com\/es\/conjunto-de-enlace-de-riel-de-excavadora-anfibia\/\" title=\"Cadenas de orugas de pontones de excavadora anfibia\" target=\"_blank\" rel=\"noopener\">cadenas de orugas de pontones de excavadora anfibia<\/a> tienen un dispositivo de remo, que puede mejorar efectivamente la capacidad de carga de toda la m\u00e1quina en el agua.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"4_DISPOSITIVO_TENSOR_DE_CADENA\"><\/span>4. DISPOSITIVO TENSOR DE CADENA<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Despu\u00e9s de que las cadenas cumplan con un tiempo de desgaste razonable, que tambi\u00e9n depende de la operaci\u00f3n, el paso de la cadena se ampliar\u00e1 utilizando el pasador de la pista, causando un deslizamiento o ca\u00edda de la pista. cadena, lo que representa un gran riesgo para el rendimiento laboral. El dispositivo de tensi\u00f3n de la cadena realizar\u00e1 un ajuste de la posici\u00f3n de la rueda de la cadena para asegurarse de que el pasador de la cadena y el engranaje de transmisi\u00f3n tengan una combinaci\u00f3n perfecta para evitar problemas. El tensado de pernos es la configuraci\u00f3n \u00f3ptima para el pont\u00f3n anfibio. Adem\u00e1s, hay un sistema de tensi\u00f3n m\u00e1s f\u00e1cil de maniobrar que puede emplear: el tensado del cilindro de aceite, con el que la fuerza de tensi\u00f3n puede lograr un ajuste de equilibrio para que todo el sistema operativo sea \u00f3ptimo, eficiente y seguro.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h6><span class=\"ez-toc-section\" id=\"5_PONTON_RETRACTIL\"><\/span>5. PONT\u00d3N RETR\u00c1CTIL<span class=\"ez-toc-section-end\"><\/span><\/h6>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.9.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Este accesorio proporciona una mayor autonom\u00eda al operador. Significa que el espacio de los 2 pontones puede ser ajustado libremente por el sistema operativo dentro de un cierto rango. Hay un sistema de control hidr\u00e1ulico en la viga conectada de los dos pontones, que se puede operar f\u00e1cilmente. En el caso de que el espacio de trabajo en el que operar sea un \u00e1rea muy estrecha, el espacio del pont\u00f3n se puede ajustar al m\u00ednimo sin dejar de funcionar normalmente. Como resultado, al ajustar de manera flexible el espacio entre los pontones, puede ayudar a mejorar la estabilidad del chasis, as\u00ed como a mejorar la eficiencia general del trabajo.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Una excavadora anfibia es un tipo de excavadora que cuenta con un equipo de pontones sellado que le permite realizar trabajos de dragado mientras flota en aguas poco profundas. Los pontones est\u00e1n construidos con acero de alta resistencia a la tracci\u00f3n, debido a las condiciones de trabajo en las que se encuentran, son resistentes a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":232399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-232439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-relacionados-con-excavadoras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI<\/title>\n<meta name=\"description\" content=\"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI\" \/>\n<meta property=\"og:description\" content=\"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/\" \/>\n<meta property=\"og:site_name\" content=\"YUTANI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/YutaniExcavatorParts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/YutaniExcavatorParts\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-22T05:54:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-22T05:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"YUTANI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"YUTANI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/\"},\"author\":{\"name\":\"YUTANI\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/be1169e3779e615f288751870559d677\"},\"headline\":\"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA?\",\"datePublished\":\"2022-06-22T05:54:53+00:00\",\"dateModified\":\"2022-06-22T05:54:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/\"},\"wordCount\":3420,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Amphibious-excavator.png\",\"articleSection\":[\"Consejos relacionados con excavadoras\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/\",\"name\":\"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Amphibious-excavator.png\",\"datePublished\":\"2022-06-22T05:54:53+00:00\",\"dateModified\":\"2022-06-22T05:54:57+00:00\",\"description\":\"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Amphibious-excavator.png\",\"contentUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Amphibious-excavator.png\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/que-es-una-excavadora-anfibia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\",\"name\":\"YUTANI\",\"description\":\"Your Reliable Excavator Undercarriage Parts Supplier Partner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#organization\",\"name\":\"YUTANI\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.ico\",\"contentUrl\":\"https:\\\/\\\/www.yutaniglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.ico\",\"width\":16,\"height\":16,\"caption\":\"YUTANI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/YutaniExcavatorParts\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yutanichina\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/be1169e3779e615f288751870559d677\",\"name\":\"YUTANI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g\",\"caption\":\"YUTANI\"},\"description\":\"YUTANI focuses on the excavator track chain industry. It is the designated supplier of many excavator original equipment manufacturer.\",\"sameAs\":[\"https:\\\/\\\/www.yutaniglobal.com\",\"https:\\\/\\\/www.facebook.com\\\/YutaniExcavatorParts\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yutanichina\\\/\"],\"url\":\"https:\\\/\\\/www.yutaniglobal.com\\\/es\\\/author\\\/yutani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI","description":"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI","og_description":"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.","og_url":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/","og_site_name":"YUTANI","article_publisher":"https:\/\/www.facebook.com\/YutaniExcavatorParts","article_author":"https:\/\/www.facebook.com\/YutaniExcavatorParts","article_published_time":"2022-06-22T05:54:53+00:00","article_modified_time":"2022-06-22T05:54:57+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png","type":"image\/png"}],"author":"YUTANI","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"YUTANI","Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#article","isPartOf":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/"},"author":{"name":"YUTANI","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/person\/be1169e3779e615f288751870559d677"},"headline":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA?","datePublished":"2022-06-22T05:54:53+00:00","dateModified":"2022-06-22T05:54:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/"},"wordCount":3420,"publisher":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png","articleSection":["Consejos relacionados con excavadoras"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/","url":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/","name":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA? - YUTANI","isPartOf":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#primaryimage"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png","datePublished":"2022-06-22T05:54:53+00:00","dateModified":"2022-06-22T05:54:57+00:00","description":"La excavadora anfibia es cada vez m\u00e1s conocida como maquinaria de construcci\u00f3n que puede adaptarse a m\u00faltiples condiciones del terreno.","breadcrumb":{"@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#primaryimage","url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png","contentUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2021\/06\/Amphibious-excavator.png","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.yutaniglobal.com\/es\/que-es-una-excavadora-anfibia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.yutaniglobal.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQU\u00c9 ES UNA EXCAVADORA ANFIBIA?"}]},{"@type":"WebSite","@id":"https:\/\/www.yutaniglobal.com\/es\/#website","url":"https:\/\/www.yutaniglobal.com\/es\/","name":"YUTANI","description":"Your Reliable Excavator Undercarriage Parts Supplier Partner","publisher":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yutaniglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yutaniglobal.com\/es\/#organization","name":"YUTANI","url":"https:\/\/www.yutaniglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2020\/08\/favicon.ico","contentUrl":"https:\/\/www.yutaniglobal.com\/wp-content\/uploads\/2020\/08\/favicon.ico","width":16,"height":16,"caption":"YUTANI"},"image":{"@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/YutaniExcavatorParts","https:\/\/www.linkedin.com\/company\/yutanichina\/"]},{"@type":"Person","@id":"https:\/\/www.yutaniglobal.com\/es\/#\/schema\/person\/be1169e3779e615f288751870559d677","name":"YUTANI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/809d307700f76ff4b012a49333ba6b8499fe14a7463d1bdf70e4d4a867caae4a?s=96&d=mm&r=g","caption":"YUTANI"},"description":"YUTANI focuses on the excavator track chain industry. It is the designated supplier of many excavator original equipment manufacturer.","sameAs":["https:\/\/www.yutaniglobal.com","https:\/\/www.facebook.com\/YutaniExcavatorParts","https:\/\/www.linkedin.com\/company\/yutanichina\/"],"url":"https:\/\/www.yutaniglobal.com\/es\/author\/yutani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts\/232439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/comments?post=232439"}],"version-history":[{"count":0,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/posts\/232439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/media\/232399"}],"wp:attachment":[{"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/media?parent=232439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/categories?post=232439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yutaniglobal.com\/es\/wp-json\/wp\/v2\/tags?post=232439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}